{"id":6965,"date":"2026-02-10T15:08:36","date_gmt":"2026-02-10T18:08:36","guid":{"rendered":"https:\/\/defiendase.com\/?p=6965"},"modified":"2026-02-10T15:08:39","modified_gmt":"2026-02-10T18:08:39","slug":"cuneo-libarona-sobre-los-menores-delincuentes-saben-lo-que-hacen","status":"publish","type":"post","link":"https:\/\/defiendase.com\/index.php\/cuneo-libarona-sobre-los-menores-delincuentes-saben-lo-que-hacen\/","title":{"rendered":"C\u00faneo Libarona, sobre los menores delincuentes: \u00abSaben lo que hacen\u00bb&nbsp;"},"content":{"rendered":"\n<p>El ministro de Justicia, Mariano C\u00faneo Libarona, sali\u00f3 a respaldar con firmeza el proyecto formalizado por el Poder Ejecutivo que propone reducir la edad de imputabilidad de 16 a 14 a\u00f1os. La iniciativa empezar\u00e1 a debatirse ma\u00f1ana en Diputados y para lograr una mayor adhesi\u00f3n, el Gobierno resign\u00f3 la idea inicial de que la baja sea hasta los 13 a\u00f1os.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En una entrevista radial, C\u00faneo Libarona consider\u00f3 que los adolescentes que cometen delitos \u00abtienen conocimiento y comprensi\u00f3n de sus actos\u00bb, y que por eso corresponde aplicarles responsabilidad penal directa. \u00abUn chico de 14 a\u00f1os sabe perfectamente lo que hace\u00bb, sostuvo sin vueltas, para descartar el argumento de que los menores no distinguen la criminalidad de sus conductas.&nbsp;<\/p>\n\n\n\n<p>El funcionario sostuvo adem\u00e1s que la iniciativa no busca \u00abcriminalizar\u00bb a los chicos, sino ajustar el r\u00e9gimen penal juvenil a lo que, en su opini\u00f3n, es la realidad actual y explic\u00f3 que muchos chicos salen a robar porque saben que son inimputables.&nbsp;&nbsp;<\/p>\n\n\n\n<p>El proyecto cuenta con el respaldo de los bloques cercanos al oficialismo y divide las aguas en el peronismo. El&nbsp;massismo&nbsp; sostiene que la baja de la edad de imputabilidad es una bandera hist\u00f3rica de ese espacio pol\u00edtico por lo que, pese a que advierten que el texto de La Libertad Avanza tiene defectos y no contempla la reinserci\u00f3n social de los chicos detenidos, analizan votar a favor.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Justicia, Mariano C\u00faneo Libarona, sali\u00f3 a respaldar con firmeza el proyecto formalizado<\/p>\n","protected":false},"author":4,"featured_media":6966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[263],"tags":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/defiendase.com\/wp-content\/uploads\/2026\/02\/cuneo-2.jfif_.jpg","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6965"}],"collection":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/comments?post=6965"}],"version-history":[{"count":1,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6965\/revisions"}],"predecessor-version":[{"id":6967,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6965\/revisions\/6967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/media\/6966"}],"wp:attachment":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/media?parent=6965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/categories?post=6965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/tags?post=6965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}