{"id":6957,"date":"2026-02-09T12:55:55","date_gmt":"2026-02-09T15:55:55","guid":{"rendered":"https:\/\/defiendase.com\/?p=6957"},"modified":"2026-02-09T20:41:30","modified_gmt":"2026-02-09T23:41:30","slug":"un-desalojo-que-divide-al-barrio-en-virrey-del-pino","status":"publish","type":"post","link":"https:\/\/defiendase.com\/index.php\/un-desalojo-que-divide-al-barrio-en-virrey-del-pino\/","title":{"rendered":"Un desalojo que divide al barrio en Virrey del Pino"},"content":{"rendered":"\n<p>En el barrio San Pedro, en Virrey del Pino, se viven d\u00edas de extrema tensi\u00f3n. &nbsp;Alrededor de 90 familias denuncian intentos de desalojo sin la correspondiente orden judicial. Los habitantes del predio ubicado en el cruce de las calles Agust\u00edn Molina y Acoyte afirman que la polic\u00eda intent\u00f3 avanzar sin exhibir documentaci\u00f3n legal.<\/p>\n\n\n\n<p>Despu\u00e9s de varios enfrentamientos, y aunque saben que el desalojo puede ser inminente, las familias temen que los est\u00e9n corriendo por intereses privados que no tienen respaldo judicial y por eso exigen que el procedimiento se ajuste a la ley. \u00abSi existe un propietario, que se presente con una orden de desalojo firmada por un juez. En ese caso, nos vamos\u00bb, expresaron a modo de resistencia .<\/p>\n\n\n\n<p>Seg\u00fan relatan , lejos de recibir respuestas formales, cuando plantearon sus dudas y exigieron los documentos, la polic\u00eda s\u00f3lo les respondi\u00f3 con &nbsp;amenazas. Hasta el momento, nadie &nbsp;present\u00f3 t\u00edtulos de propiedad ni resoluciones judiciales que respalden el operativo.<\/p>\n\n\n\n<p>Mientras tanto, otros vecinos del barrio celebran el accionar policial y subrayan que los actuales ocupantes del predio se tienen que ir porque son usurpadores. Por ahora, la justicia no fue clara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el barrio San Pedro, en Virrey del Pino, se viven d\u00edas de extrema tensi\u00f3n.<\/p>\n","protected":false},"author":4,"featured_media":6960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[263],"tags":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/defiendase.com\/wp-content\/uploads\/2026\/02\/image-4.png","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6957"}],"collection":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/comments?post=6957"}],"version-history":[{"count":2,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6957\/revisions"}],"predecessor-version":[{"id":6961,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/posts\/6957\/revisions\/6961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/media\/6960"}],"wp:attachment":[{"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/media?parent=6957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/categories?post=6957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defiendase.com\/index.php\/wp-json\/wp\/v2\/tags?post=6957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}